{"id":120,"date":"2021-02-25T18:36:48","date_gmt":"2021-02-25T18:36:48","guid":{"rendered":"http:\/\/fafasd.net\/?p=120"},"modified":"2021-02-25T18:36:48","modified_gmt":"2021-02-25T18:36:48","slug":"fasd-warum-diagnostizieren","status":"publish","type":"post","link":"https:\/\/fafasd.net\/index.php\/2021\/02\/25\/fasd-warum-diagnostizieren\/","title":{"rendered":"FASD: Warum diagnostizieren?"},"content":{"rendered":"<p>(German translation of <a href=\"https:\/\/fafasd.net\/index.php\/2021\/02\/25\/fasd-why-get-it-diagnosed\/\"><em>FASD: Why Get it Diagnosed?<\/em><\/a> kindly provided by <a href=\"http:\/\/fasd-netzwerk.at\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/fasd-netzwerk.at&amp;source=gmail&amp;ust=1614364218923000&amp;usg=AFQjCNEThP3jLBqs4cMQrKpiU0dDj_5zuw\">fasd-netzwerk.at<\/a>)<\/p>\n<p>Warum eine Diagnose im FASD-Spektrum suchen?<\/p>\n<p>F\u00fcr viele &#8211; Eltern, unterst\u00fctzende Fachkr\u00e4fte und Betroffene &#8211; ,die bereits eine<br \/>\nbest\u00e4tigte FASD-Diagnose haben, ist dies eine verwirrende Frage. Warum sollte<br \/>\njemand keine korrekte medizinische Diagnose einer FASD wollen? F\u00fcr die<br \/>\nmeisten von uns hat eine fachlich fundierte und genaue Diagnose T\u00fcren zum<br \/>\nVerst\u00e4ndnis ge\u00f6ffnet \u2013 das Verst\u00e4ndnis in uns selbst, in unseren Familien, aber<br \/>\nauch f\u00fcr Fachleute und die Unterst\u00fctzungssysteme um uns herum. F\u00fcr viele<br \/>\nvon uns ist eine solche Diagnose von FASD eine wertvolle Unterst\u00fctzung im<br \/>\nBetreuungsangebot, indem sie das Bewusstsein gegen\u00fcber FASD sch\u00e4rft und<br \/>\ndamit zur Lebensqualit\u00e4t und Erleichterung beitr\u00e4gt: Es gibt einen Grund f\u00fcr<br \/>\ndiese Verhaltensweisen, f\u00fcr dieses \u201eAnders-Sein\u201c, und es hat mit dem Gehirn<br \/>\nzu tun. Es hilft uns allen beim Umdenken: von FASD-Betroffene WOLLEN sich<br \/>\nnicht so verhalten wie andere zu FASD-Betroffene K\u00d6NNEN sich nicht so<br \/>\nverhalten wie andere, weil ihr Gehirn anders funktioniert.<br \/>\nDiese Frage wird jedoch h\u00e4ufig von Eltern und Familienmitgliedern gestellt, die<br \/>\neine FASD vermuten, aber noch keine Diagnose erhalten haben. Insbesondere<br \/>\nist das dort der Fall, wo nur geringe Kapazit\u00e4ten f\u00fcr eine FASD-Diagnose<br \/>\nbestehen, es an Unterst\u00fctzung f\u00fcr FASD-Betroffene und deren Familien sowie<br \/>\ngenerell an Verst\u00e4ndnis f\u00fcr FASD mangelt. Fachleute, die wenig \u00fcber FASD<br \/>\nwissen, raten h\u00e4ufig von der Diagnose ab. Sie sagen, dass \u201eman ohnehin nichts<br \/>\ndagegen tun k\u00f6nne\u201c oder, dass das WARUM von Verhaltensweisen keine Rolle<br \/>\nspiele bei der \u00dcberlegung, was man dagegen tun k\u00f6nne. Aber Eltern,<br \/>\nFamilienmitglieder, Betreuer, Fachkr\u00e4fte und FASD\u2013Betroffene wissen, dass die<br \/>\nDiagnose von entscheidender Bedeutung ist, und tats\u00e4chlich die Frage, WIE mit<br \/>\nVerhaltensweisen umzugehen ist, alles mit dem WARUM zu tun hat.<\/p>\n<p>Wir haben unser Online-Eltern-Forum, Shifting the Paradigm (auf Facebook),<br \/>\nnach Gr\u00fcnden f\u00fcr die Diagnose gefragt. Die Eltern haben Folgendes gesagt:<br \/>\n1. Weil die Informationen, die man bei einer Diagnose erh\u00e4lt, sehr wertvoll<br \/>\nsind. Die Diagnose umfasst neuropsychologische Tests, adaptive<br \/>\nF\u00e4higkeiten, Sprach- und ergotherapeutische Bewertungen. All dies hilft<br \/>\ndabei, die Person mit FASD zu verstehen.<br \/>\n2. Verst\u00e4ndnis f\u00fcr FASD erm\u00f6glicht passendere Unterbringungen und<br \/>\n\u00c4nderungen in der Umgebung. Sobald wir die Verhaltensweisen<br \/>\nverstehen, die mit FASD als Folge einer in der Geb\u00e4rmutter erworbenen<\/p>\n<p>Hirnsch\u00e4digung verbunden sind, k\u00f6nnen wir diese Verhaltensweisen als<br \/>\nSymptome einer dauerhaften k\u00f6rperlichen Behinderung ansehen. Und<br \/>\nnicht als \u201ewillk\u00fcrliches\u201c Verhalten, oder einen Beweis daf\u00fcr, dass das<br \/>\nKind \u201eschlecht erzogen\u201c ist. Es ver\u00e4ndert unser Bild von<br \/>\nVerhaltensweisen: von \u201edie Person IST ein Problem\u201c zu \u201edie Person HAT<br \/>\nein Problem\u201c. Mit diesem neuen Verst\u00e4ndnis \u00e4ndern sich auch die<br \/>\nReaktionen der Betreuer, Eltern, Fachkr\u00e4fte und Unterst\u00fctzungskr\u00e4fte.<\/p>\n<p>3. Auch wenn es m\u00f6glicherweise nicht viele Menschen in Ihrer Umgebung<br \/>\ngibt, die verstehen, was FASD ist, gibt es tats\u00e4chlich eine Vielzahl von<br \/>\nInformationen und Forschungsergebnissen. Zusammen mit der Diagnose<br \/>\nFASD versetzt dies Fachleute und alle anderen Menschen in Ihrer<br \/>\nUmgebung oder jener des Kindes in die Lage, mit Verst\u00e4ndnis auf die<br \/>\nspeziellen Bed\u00fcrfnisse einzugehen.<br \/>\n4. Medikamente, die eingenommen werden, wirken bei Menschen mit<br \/>\nFASD normalerweise anders als bei Menschen ohne FASD; die Diagnose<br \/>\nbietet eine Erkl\u00e4rung daf\u00fcr.<\/p>\n<p>5. Die Diagnoserate ist unglaublich niedrig, und die Mehrheit der Menschen<br \/>\nmit FASD wird entweder nicht oder falsch diagnostiziert. Um eine<br \/>\nErh\u00f6hung der Diagnosekapazit\u00e4ten zu erreichen und passende<br \/>\nDiagnoseraten zu erreichen m\u00fcssen wir die Diagnostik einfordern.<br \/>\n6. Mit einer korrekten Diagnose k\u00f6nnen Sie sich mit anderen Familien<br \/>\nvernetzen, die \u00e4hnliche Diagnosen haben. In der Gemeinschaft liegt<br \/>\ngro\u00dfes Potenzial f\u00fcr eine bessere Bew\u00e4ltigung.<\/p>\n<p>7. Durch die korrekte Diagnose haben Sie leichteren Zugang zu<br \/>\nunterst\u00fctzenden Leistungen.<br \/>\n8. Die Diagnose FASD wird zunehmend als mildernder Faktor in der<br \/>\nStrafjustiz anerkannt. Wenngleich die Verh\u00fctung von Straftaten durch<br \/>\nangemessene \u00dcberwachung und Unterst\u00fctzung das Ziel aller ist, kann im<br \/>\nFalle eines Justizverfahrens eine Diagnose im Spektrum allen Beteiligten<br \/>\nhelfen, die Situation besser zu verstehen und zu einer angemesseneren<br \/>\nVerurteilung f\u00fchren.<\/p>\n<p>9. Wenn wir unseren Kopf in den Sand stecken, denken Menschen mit FASD<br \/>\nm\u00f6glicherweise, dass sie schlecht sind oder dass etwas mit ihnen nicht<br \/>\nstimmt. Mit der Diagnose \u00e4ndert sich f\u00fcr viele Betroffene das Leben: sie<br \/>\nwissen, dass es nicht ihre Schuld ist und f\u00fchlen sich besser.<br \/>\n10.\u201eStempel\u201c tragen Menschen, die anders sind. Die richtige und genaue<br \/>\nDiagnose erm\u00f6glicht es, die Kontrolle \u00fcber diesen \u201eStempel\u201c zu<br \/>\n\u00fcbernehmen. Mit der Diagnose FASD erh\u00e4lt man eine F\u00fclle von<br \/>\nInformationen, die das \u201eWarum\u201c von Verhaltensunterschieden erkl\u00e4ren.<br \/>\nAnstatt von uninformierten Menschen als \u201edumm, mutwillig, trotzig,<br \/>\ndelinquent, unverbesserlich, Unruhestifter, schlecht, faul\u201c eingesch\u00e4tzt<br \/>\nund behandelt zu werden, k\u00f6nnen FASD-Betroffene so gesehen werden,<br \/>\nwie sie wirklich sind: freundlich, offen, bem\u00fcht, kreativ, hilfsbereit&#8230;.und<br \/>\naufgrund vorgeburtlicher Alkoholexposition beeintr\u00e4chtigt.<\/p>\n<p>Weitere Informationen zur Fetalen Alkoholspektrumst\u00f6rung und zum anderen<br \/>\nVerst\u00e4ndnis von Verhaltensweisen finden Sie in Diane Malbins Buch: FASD:<br \/>\nTrying Differently Rather than Harder oder nehmen Sie an einer unserer<br \/>\nSchulungen teil: fafasd.net<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(German translation of FASD: Why Get it Diagnosed? kindly provided by fasd-netzwerk.at) Warum eine Diagnose im FASD-Spektrum suchen? F&uuml;r viele &ndash; Eltern, unterst&uuml;tzende Fachkr&auml;fte und Betroffene &ndash; ,die bereits eine best&auml;tigte FASD-Diagnose haben, ist dies eine verwirrende Frage. Warum sollte<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,7],"tags":[13,10,8,15,14,25,24,17],"_links":{"self":[{"href":"https:\/\/fafasd.net\/index.php\/wp-json\/wp\/v2\/posts\/120"}],"collection":[{"href":"https:\/\/fafasd.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fafasd.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fafasd.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fafasd.net\/index.php\/wp-json\/wp\/v2\/comments?post=120"}],"version-history":[{"count":1,"href":"https:\/\/fafasd.net\/index.php\/wp-json\/wp\/v2\/posts\/120\/revisions"}],"predecessor-version":[{"id":121,"href":"https:\/\/fafasd.net\/index.php\/wp-json\/wp\/v2\/posts\/120\/revisions\/121"}],"wp:attachment":[{"href":"https:\/\/fafasd.net\/index.php\/wp-json\/wp\/v2\/media?parent=120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fafasd.net\/index.php\/wp-json\/wp\/v2\/categories?post=120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fafasd.net\/index.php\/wp-json\/wp\/v2\/tags?post=120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}